{"id":11457,"date":"2019-01-30T14:10:37","date_gmt":"2019-01-30T14:10:37","guid":{"rendered":"http:\/\/www.mspprato.it\/site\/?p=11457"},"modified":"2021-03-18T17:49:43","modified_gmt":"2021-03-18T17:49:43","slug":"oltrelaragione-docufilm","status":"publish","type":"post","link":"https:\/\/www.mspprato.it\/site\/oltrelaragione-docufilm\/","title":{"rendered":"Oltre la ragione &#8211; docufilm"},"content":{"rendered":"<h3>Il docufilm su Christian Giagnoni<\/h3>\n<p>&nbsp;<\/p>\n<h4>Il progetto<\/h4>\n<p style=\"text-align: justify;\">Christian si ritiene molto fortunato. A 43 anni ha gi\u00e0 vissuto due vite: la prima dedicata all\u2019hockey su pista, di cui \u00e8 stato campione nella citt\u00e0 natale, Prato. La seconda su altre ruote, quelle dell\u2019hand-bike. Vincitore di tre Giri d\u2019Italia, si allena costantemente con un grande obiettivo all\u2019orizzonte: le Olimpiadi di Tokyo 2020. In mezzo a tutto ci\u00f2, un solo giorno, una goccia nel mare della vita, che cambia tutto: 23 dicembre 2010. Un grave incidente, una lunga degenza, ma lo stesso sorriso e una voglia di vivere rimasta immutata.<\/p>\n<p style=\"text-align: justify;\">Una storia che merita di essere raccontata ed esportata come esempio di vera resilienza alla vita.\u00a0Il messaggio da veicolare \u00e8 un monito, scolpito nelle parole \u201cnever back down\u201d, mai arrendersi, soprattutto quando tutto sembra perduto. Non sono frasi ad effetto, sono dati di fatto che si rispecchiano nelle azioni di Christian, quando riportava la sua squadra di hockey in serie A, quando si \u00e8 tirato fuori da quel letto, quando si \u00e8 rimesso in gioco in uno sport che non aveva mai provato.<\/p>\n<p style=\"text-align: justify;\">\u201cIl pratese dell\u2019anno\u201d, come lo definisce il quotidiano La Nazione, \u00e8 simbolo della sua citt\u00e0, Prato, che non si arrende di fronte ai cambiamenti, ma vede in ogni avversit\u00e0 un\u2019opportunit\u00e0 che pu\u00f2 aprire nuove strade. Christian, come si evince dalle interviste, \u00e8 legato a doppio filo alle realt\u00e0 cittadine che lo circondano, che lo hanno visto protagonista in ogni impresa nella quale si sia cimentato.<\/p>\n<p style=\"text-align: justify;\">Il racconto documentario non si ferma ad un solo approccio motivazionale, ma \u00e8 integrato dalle emozioni delle persone che hanno vissuto tutto ci\u00f2 in prima persona: tutti coloro che hanno affiancato il vulcano Giagnoni nelle diverse parti della sua avventura, che fanno capire chi veramente egli sia. Seguendo il protagonista nei suoi allenamenti quotidiani, che lo preparano al campionato mondiale di hand-bike, si percepiscono le sue emozioni nel mondo di oggi, allacciandosi a come egli \u00e8 arrivato a questo punto con riferimenti alle sue \u201cvite precedenti\u201d. Tutto ci\u00f2 volgendo lo sguardo al traguardo definitivo, la partecipazione alle Olimpiadi di Tokyo 2020 (giochi paralimpici).<\/p>\n<p style=\"text-align: justify;\">Infine, questo progetto ha anche la finalit\u00e0 di esportare la storia di Christian oltre i confini pratesi, cercando di promuovere la sua candidatura come atleta nazionale che cerca di partecipare alle prossime Paralimpiadi, cosa non scontata, nonostante il suo palmares condito dalle vittorie di ben tre Giri d\u2019Italia.<\/p>\n<p>&nbsp;<\/p>\n<h4>Produzione<\/h4>\n<p style=\"text-align: justify;\">La produzione del progetto ha seguito tre canali per la raccolta dei fondi necessari: l\u2019appoggio dell\u2019azienda New Solid \u00e8 stato fondamentale per dare inizio alle riprese, che sono iniziate a dicembre 2018 e il successivo inserimento in parallelo di Msp Prato ha permesso al progetto di continuare il proprio percorso. La terza via intrapresa \u00e8 stata quella del crownfounding, attuato sulla piattaforma online \u201cproduzionidalbasso\u201d, dal quale la produzione cerca di raccogliere i restanti fondi necessari per terminare le giornate di ripresa, la post-produzione e la distribuzione. Quest\u2019ultima \u00e8 fondamentale per le finalit\u00e0 del progetto, che mira ad esportare questa storia come un esempio per tutte le persone che quotidianamente si scontrano con delle difficolt\u00e0, ma anche per spingere il protagonista Christian alle Olimpiadi di Tokyo 2020.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il docufilm su Christian Giagnoni &nbsp; Il progetto Christian si ritiene molto fortunato. A 43 anni ha gi\u00e0 vissuto due vite: la prima dedicata all\u2019hockey su pista, di cui \u00e8 stato campione nella citt\u00e0 natale, Prato. La seconda su altre ruote, quelle dell\u2019hand-bike. Vincitore di tre Giri d\u2019Italia, si allena costantemente con un grande obiettivo [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":11468,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,149],"tags":[],"_links":{"self":[{"href":"https:\/\/www.mspprato.it\/site\/wp-json\/wp\/v2\/posts\/11457"}],"collection":[{"href":"https:\/\/www.mspprato.it\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mspprato.it\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mspprato.it\/site\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mspprato.it\/site\/wp-json\/wp\/v2\/comments?post=11457"}],"version-history":[{"count":5,"href":"https:\/\/www.mspprato.it\/site\/wp-json\/wp\/v2\/posts\/11457\/revisions"}],"predecessor-version":[{"id":12508,"href":"https:\/\/www.mspprato.it\/site\/wp-json\/wp\/v2\/posts\/11457\/revisions\/12508"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mspprato.it\/site\/wp-json\/wp\/v2\/media\/11468"}],"wp:attachment":[{"href":"https:\/\/www.mspprato.it\/site\/wp-json\/wp\/v2\/media?parent=11457"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mspprato.it\/site\/wp-json\/wp\/v2\/categories?post=11457"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mspprato.it\/site\/wp-json\/wp\/v2\/tags?post=11457"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}