{"id":10614,"date":"2019-01-17T13:36:12","date_gmt":"2019-01-17T13:36:12","guid":{"rendered":"http:\/\/www.mspprato.it\/site\/?p=10614"},"modified":"2019-01-18T10:44:40","modified_gmt":"2019-01-18T10:44:40","slug":"corso-istruttore-body-building-e-fitness-1-livello","status":"publish","type":"post","link":"https:\/\/www.mspprato.it\/site\/corso-istruttore-body-building-e-fitness-1-livello\/","title":{"rendered":"Corso Istruttore Body Building e Fitness &#8211; (1\u00b0 livello)"},"content":{"rendered":"<p align=\"JUSTIFY\"><span style=\"color: #181e1f;\"><span style=\"font-family: Verdana, sans-serif;\"><span style=\"font-size: medium;\">Il corso, realizzato in collaborazione col Brutal Club, \u00e8\u00a0rivolto a tutti coloro che vogliono avvicinarsi per la prima volta, o gi\u00e0 ne fanno parte, al mondo dell\u2019insegnamento e vogliono diventare preparatore di attivit\u00e0 relative al benessere psico-fisico nell\u2019ambito del mondo del body building e fitness. Si rivolge, inoltre, a coloro che desiderano apprendere un sistema, approfondire la didattica e la metodologia.\u00a0\u00c8\u00a0rivolto, infine, a coloro che necessitano di competenze ancora pi\u00f9 specifiche nel settore del fitness e vogliono allargare e migliorare la propria educazione e conoscenza, crescendo ulteriormente la propria esperienza. Le possibilit\u00e0 d\u2019inserimento in centri sportivi sono molteplici, i nostri corsi preparano esperti in grado di prestare servizio in associazioni, centri fitness ed enti sportivi.<\/span><\/span><\/span><\/p>\n<p style=\"text-align: center;\" align=\"JUSTIFY\"><strong><span style=\"font-family: Verdana, sans-serif;\"><span style=\"font-size: medium;\"><b>Per info contattare:<\/b><\/span><\/span><\/strong><\/p>\n<h4 style=\"text-align: center;\" align=\"JUSTIFY\"><strong><a href=\"mailto:prato@mspitalia.it\"><span style=\"color: #39abc3;\"><span style=\"font-family: Verdana, sans-serif;\"><span style=\"font-size: medium;\"><b>prato@mspitalia.it<\/b><\/span><\/span><\/span><\/a><\/strong><\/h4>\n<pre style=\"text-align: center;\"><strong>Simone Natali\u00a03475512856 - Thomas Bagnoli 3357852606<\/strong><\/pre>\n<h4 style=\"text-align: center;\" align=\"JUSTIFY\"><strong><span style=\"color: #181e1f;\"><span style=\"font-family: Verdana, sans-serif;\"><span style=\"font-size: medium;\"><b>Documenti &amp; Modulistica:<\/b><\/span><\/span><\/span><\/strong><\/h4>\n<h4 class=\"western\" style=\"text-align: center;\" align=\"JUSTIFY\"><a href=\"http:\/\/www.mspprato.it\/site\/wp-content\/uploads\/2018\/02\/Body-Building-e-Fitness-1\u00b0-Livello-02-2019.pdf\">Programma del Corso Istruttore Body Building e Fitness &#8211; (1\u00b0 livello)<\/a><\/h4>\n<h4 class=\"western\" style=\"text-align: center;\" align=\"JUSTIFY\"><a href=\"http:\/\/www.mspprato.it\/site\/wp-content\/uploads\/2018\/02\/scheda_iscrizione_corsi.pdf\">Domanda Iscrizione Corsi di Formazione<\/a><\/h4>\n<h4 style=\"text-align: center;\" align=\"JUSTIFY\"><strong><span style=\"font-family: Verdana, sans-serif;\"><span style=\"font-size: medium;\"><b>Pagamento:<\/b><\/span><\/span><\/strong><\/h4>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.paypal.com\/cgi-bin\/webscr?cmd=_s-xclick&amp;hosted_button_id=GL4FULXTY4KWC\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-medium wp-image-150\" src=\"http:\/\/www.msptoscana.it\/wp-content\/uploads\/2017\/01\/pagamenti_box-300x107.png\" alt=\"\" width=\"300\" height=\"107\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><em>Oppure:<\/em><\/p>\n<p style=\"text-align: center;\">B\/B intestato a MSP su Banca Prossima:\u00a0<b>IT04L0335901600100000076934<\/b><\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter wp-image-6268\" src=\"http:\/\/www.mspprato.it\/site\/wp-content\/uploads\/2011\/09\/Screenshot-2014-08-08-16.49.32.png\" alt=\"Screenshot 2014-08-08 16.49.32\" width=\"500\" height=\"251\" srcset=\"https:\/\/www.mspprato.it\/site\/wp-content\/uploads\/2011\/09\/Screenshot-2014-08-08-16.49.32.png 653w, https:\/\/www.mspprato.it\/site\/wp-content\/uploads\/2011\/09\/Screenshot-2014-08-08-16.49.32-300x150.png 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il corso, realizzato in collaborazione col Brutal Club, \u00e8\u00a0rivolto a tutti coloro che vogliono avvicinarsi per la prima volta, o gi\u00e0 ne fanno parte, al mondo dell\u2019insegnamento e vogliono diventare preparatore di attivit\u00e0 relative al benessere psico-fisico nell\u2019ambito del mondo del body building e fitness. Si rivolge, inoltre, a coloro che desiderano apprendere un sistema, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":11441,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[149],"tags":[],"_links":{"self":[{"href":"https:\/\/www.mspprato.it\/site\/wp-json\/wp\/v2\/posts\/10614"}],"collection":[{"href":"https:\/\/www.mspprato.it\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mspprato.it\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mspprato.it\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mspprato.it\/site\/wp-json\/wp\/v2\/comments?post=10614"}],"version-history":[{"count":7,"href":"https:\/\/www.mspprato.it\/site\/wp-json\/wp\/v2\/posts\/10614\/revisions"}],"predecessor-version":[{"id":11442,"href":"https:\/\/www.mspprato.it\/site\/wp-json\/wp\/v2\/posts\/10614\/revisions\/11442"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mspprato.it\/site\/wp-json\/wp\/v2\/media\/11441"}],"wp:attachment":[{"href":"https:\/\/www.mspprato.it\/site\/wp-json\/wp\/v2\/media?parent=10614"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mspprato.it\/site\/wp-json\/wp\/v2\/categories?post=10614"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mspprato.it\/site\/wp-json\/wp\/v2\/tags?post=10614"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}